{"id":5435,"date":"2009-08-31T11:33:51","date_gmt":"2009-08-31T15:33:51","guid":{"rendered":"http:\/\/www.freestufftimes.com\/coupons\/?p=5435"},"modified":"2009-08-31T11:33:51","modified_gmt":"2009-08-31T15:33:51","slug":"15-off-at-walgreens-today-only","status":"publish","type":"post","link":"https:\/\/www.freestufftimes.com\/coupons\/31\/15-off-at-walgreens-today-only\/","title":{"rendered":"15% off at Walgreens today only"},"content":{"rendered":"<p><a target=\"_blank\" href=\"http:\/\/www.walgreens.com\/topic\/instorespecials\/friends.jsp?ban=flh1_h_family_friends\" >www.walgreens.com\/topic\/instorespecials\/friends.jsp?ban=flh1_h_family_friends<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><a target=\"_blank\" href=\"http:\/\/www.walgreens.com\/topic\/instorespecials\/friends.jsp?ban=flh1_h_family_friends\"  class=\"autohyperlink\">www.walgreens.com\/topic\/instorespecials\/friends.jsp?ban=flh1_h_family_friends<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,82],"tags":[],"class_list":["post-5435","post","type-post","status-publish","format-standard","hentry","category-stores","category-walgreens"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>15% off at Walgreens today only<\/title>\n<meta name=\"description\" content=\"15% off at Walgreens today only\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freestufftimes.com\/coupons\/31\/15-off-at-walgreens-today-only\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/31\/15-off-at-walgreens-today-only\/\",\"url\":\"https:\/\/www.freestufftimes.com\/coupons\/31\/15-off-at-walgreens-today-only\/\",\"name\":\"15% off at Walgreens today only\",\"isPartOf\":{\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#website\"},\"datePublished\":\"2009-08-31T15:33:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/39c48253e632b95216f5ef2f1b59be30\"},\"description\":\"15% off at Walgreens today only\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.freestufftimes.com\/coupons\/31\/15-off-at-walgreens-today-only\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#website\",\"url\":\"https:\/\/www.freestufftimes.com\/coupons\/\",\"name\":\"Free Stuff Times Coupons\",\"description\":\"Free Stuff coupons, with print coupons, mailed coupons, and tips on the best ways to save money with coupons!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.freestufftimes.com\/coupons\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/39c48253e632b95216f5ef2f1b59be30\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"caption\":\"Chris\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15% off at Walgreens today only","description":"15% off at Walgreens today only","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freestufftimes.com\/coupons\/31\/15-off-at-walgreens-today-only\/","twitter_misc":{"Written by":"Chris"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.freestufftimes.com\/coupons\/31\/15-off-at-walgreens-today-only\/","url":"https:\/\/www.freestufftimes.com\/coupons\/31\/15-off-at-walgreens-today-only\/","name":"15% off at Walgreens today only","isPartOf":{"@id":"https:\/\/www.freestufftimes.com\/coupons\/#website"},"datePublished":"2009-08-31T15:33:51+00:00","author":{"@id":"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/39c48253e632b95216f5ef2f1b59be30"},"description":"15% off at Walgreens today only","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freestufftimes.com\/coupons\/31\/15-off-at-walgreens-today-only\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.freestufftimes.com\/coupons\/#website","url":"https:\/\/www.freestufftimes.com\/coupons\/","name":"Free Stuff Times Coupons","description":"Free Stuff coupons, with print coupons, mailed coupons, and tips on the best ways to save money with coupons!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.freestufftimes.com\/coupons\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/39c48253e632b95216f5ef2f1b59be30","name":"Chris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","caption":"Chris"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 12:51:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/posts\/5435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/comments?post=5435"}],"version-history":[{"count":0,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/posts\/5435\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/media?parent=5435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/categories?post=5435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/tags?post=5435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}