{"id":361874,"date":"2016-06-04T08:41:57","date_gmt":"2016-06-04T12:41:57","guid":{"rendered":"http:\/\/www.freestufftimes.com\/coupons\/?p=361874"},"modified":"2016-06-04T08:41:57","modified_gmt":"2016-06-04T12:41:57","slug":"6-00-off-one-nasacort-allergy-2x120-spray","status":"publish","type":"post","link":"https:\/\/www.freestufftimes.com\/coupons\/04\/6-00-off-one-nasacort-allergy-2x120-spray\/","title":{"rendered":"$6.00 off one Nasacort Allergy 2&#215;120 spray"},"content":{"rendered":"<p><a href=\"http:\/\/strk.enlnks2.com\/aff_c?offer_id=118&amp;aff_id=988&amp;url_id=103&amp;aff_sub5=MTk0NTkzOTg=&amp;affsrc=1\"  target=\"_blank\">$6.00 off one Nasacort Allergy 2&#215;120 spray<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>$6.00 off one Nasacort Allergy 2&#215;120 spray<\/p>\n","protected":false},"author":1724,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,8],"tags":[],"class_list":["post-361874","post","type-post","status-publish","format-standard","hentry","category-health-hygiene","category-products"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>$6.00 off one Nasacort Allergy 2x120 spray &#8226; Free Stuff Times Coupons<\/title>\n<meta name=\"description\" content=\"$6.00 off one Nasacort Allergy 2x120 spray\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freestufftimes.com\/coupons\/04\/6-00-off-one-nasacort-allergy-2x120-spray\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/04\/6-00-off-one-nasacort-allergy-2x120-spray\/\",\"url\":\"https:\/\/www.freestufftimes.com\/coupons\/04\/6-00-off-one-nasacort-allergy-2x120-spray\/\",\"name\":\"$6.00 off one Nasacort Allergy 2x120 spray &#8226; Free Stuff Times Coupons\",\"isPartOf\":{\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#website\"},\"datePublished\":\"2016-06-04T12:41:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/92709430131a501033112bbaceace8a1\"},\"description\":\"$6.00 off one Nasacort Allergy 2x120 spray\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.freestufftimes.com\/coupons\/04\/6-00-off-one-nasacort-allergy-2x120-spray\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#website\",\"url\":\"https:\/\/www.freestufftimes.com\/coupons\/\",\"name\":\"Free Stuff Times Coupons\",\"description\":\"Free Stuff coupons, with print coupons, mailed coupons, and tips on the best ways to save money with coupons!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.freestufftimes.com\/coupons\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/92709430131a501033112bbaceace8a1\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d7c18e7bf5719fa38999e7c434a3f5e09315ac6b43f1e9df39c4d9a5a2b1879e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d7c18e7bf5719fa38999e7c434a3f5e09315ac6b43f1e9df39c4d9a5a2b1879e?s=96&d=mm&r=g\",\"caption\":\"Chris\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"$6.00 off one Nasacort Allergy 2x120 spray &#8226; Free Stuff Times Coupons","description":"$6.00 off one Nasacort Allergy 2x120 spray","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freestufftimes.com\/coupons\/04\/6-00-off-one-nasacort-allergy-2x120-spray\/","twitter_misc":{"Written by":"Chris"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.freestufftimes.com\/coupons\/04\/6-00-off-one-nasacort-allergy-2x120-spray\/","url":"https:\/\/www.freestufftimes.com\/coupons\/04\/6-00-off-one-nasacort-allergy-2x120-spray\/","name":"$6.00 off one Nasacort Allergy 2x120 spray &#8226; Free Stuff Times Coupons","isPartOf":{"@id":"https:\/\/www.freestufftimes.com\/coupons\/#website"},"datePublished":"2016-06-04T12:41:57+00:00","author":{"@id":"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/92709430131a501033112bbaceace8a1"},"description":"$6.00 off one Nasacort Allergy 2x120 spray","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freestufftimes.com\/coupons\/04\/6-00-off-one-nasacort-allergy-2x120-spray\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.freestufftimes.com\/coupons\/#website","url":"https:\/\/www.freestufftimes.com\/coupons\/","name":"Free Stuff Times Coupons","description":"Free Stuff coupons, with print coupons, mailed coupons, and tips on the best ways to save money with coupons!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.freestufftimes.com\/coupons\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/92709430131a501033112bbaceace8a1","name":"Chris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d7c18e7bf5719fa38999e7c434a3f5e09315ac6b43f1e9df39c4d9a5a2b1879e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d7c18e7bf5719fa38999e7c434a3f5e09315ac6b43f1e9df39c4d9a5a2b1879e?s=96&d=mm&r=g","caption":"Chris"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-15 04:05:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/posts\/361874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/users\/1724"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/comments?post=361874"}],"version-history":[{"count":0,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/posts\/361874\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/media?parent=361874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/categories?post=361874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/tags?post=361874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}