{"id":19736,"date":"2011-06-03T13:06:28","date_gmt":"2011-06-03T17:06:28","guid":{"rendered":"http:\/\/www.freestufftimes.com\/coupons\/?p=19736"},"modified":"2011-06-03T13:06:28","modified_gmt":"2011-06-03T17:06:28","slug":"30-in-hill%e2%80%99s-science-diet-coupons","status":"publish","type":"post","link":"https:\/\/www.freestufftimes.com\/coupons\/03\/30-in-hill%e2%80%99s-science-diet-coupons\/","title":{"rendered":"$30 in Hill\u2019s Science Diet Coupons"},"content":{"rendered":"<p><a href=\"http:\/\/www.freestufftimes.com\/go\/coupons2\" >www.freestufftimes.com\/go\/coupons2<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"http:\/\/www.freestufftimes.com\/go\/coupons2\"  class=\"autohyperlink\">www.freestufftimes.com\/go\/coupons2<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,8],"tags":[],"class_list":["post-19736","post","type-post","status-publish","format-standard","hentry","category-pet-stuff","category-products"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>$30 in Hill\u2019s Science Diet Coupons<\/title>\n<meta name=\"description\" content=\"$30 in Hill\u2019s Science Diet Coupons\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freestufftimes.com\/coupons\/03\/30-in-hill\u2019s-science-diet-coupons\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/03\/30-in-hill%e2%80%99s-science-diet-coupons\/\",\"url\":\"https:\/\/www.freestufftimes.com\/coupons\/03\/30-in-hill%e2%80%99s-science-diet-coupons\/\",\"name\":\"$30 in Hill\u2019s Science Diet Coupons\",\"isPartOf\":{\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#website\"},\"datePublished\":\"2011-06-03T17:06:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/39c48253e632b95216f5ef2f1b59be30\"},\"description\":\"$30 in Hill\u2019s Science Diet Coupons\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.freestufftimes.com\/coupons\/03\/30-in-hill%e2%80%99s-science-diet-coupons\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#website\",\"url\":\"https:\/\/www.freestufftimes.com\/coupons\/\",\"name\":\"Free Stuff Times Coupons\",\"description\":\"Free Stuff coupons, with print coupons, mailed coupons, and tips on the best ways to save money with coupons!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.freestufftimes.com\/coupons\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/39c48253e632b95216f5ef2f1b59be30\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"caption\":\"Chris\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"$30 in Hill\u2019s Science Diet Coupons","description":"$30 in Hill\u2019s Science Diet Coupons","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freestufftimes.com\/coupons\/03\/30-in-hill\u2019s-science-diet-coupons\/","twitter_misc":{"Written by":"Chris"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.freestufftimes.com\/coupons\/03\/30-in-hill%e2%80%99s-science-diet-coupons\/","url":"https:\/\/www.freestufftimes.com\/coupons\/03\/30-in-hill%e2%80%99s-science-diet-coupons\/","name":"$30 in Hill\u2019s Science Diet Coupons","isPartOf":{"@id":"https:\/\/www.freestufftimes.com\/coupons\/#website"},"datePublished":"2011-06-03T17:06:28+00:00","author":{"@id":"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/39c48253e632b95216f5ef2f1b59be30"},"description":"$30 in Hill\u2019s Science Diet Coupons","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freestufftimes.com\/coupons\/03\/30-in-hill%e2%80%99s-science-diet-coupons\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.freestufftimes.com\/coupons\/#website","url":"https:\/\/www.freestufftimes.com\/coupons\/","name":"Free Stuff Times Coupons","description":"Free Stuff coupons, with print coupons, mailed coupons, and tips on the best ways to save money with coupons!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.freestufftimes.com\/coupons\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/39c48253e632b95216f5ef2f1b59be30","name":"Chris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freestufftimes.com\/coupons\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","caption":"Chris"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:18:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/posts\/19736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/comments?post=19736"}],"version-history":[{"count":0,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/posts\/19736\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/media?parent=19736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/categories?post=19736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/coupons\/wp-json\/wp\/v2\/tags?post=19736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}