{"id":749816,"date":"2025-05-18T01:33:02","date_gmt":"2025-05-18T05:33:02","guid":{"rendered":"https:\/\/www.freestufftimes.com\/contests\/?p=749816"},"modified":"2025-05-18T01:33:02","modified_gmt":"2025-05-18T05:33:02","slug":"fanttik-5th-anniversary-sweepstakes","status":"publish","type":"post","link":"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/","title":{"rendered":"Fanttik 5th Anniversary Sweepstakes"},"content":{"rendered":"<p><a target=\"_blank\" href=\"https:\/\/gleam.io\/OyiZw\/fanttik-5th-anniversary-sweepstakes?gsr=OyiZw-piJU4FcLYQ\" >https:\/\/gleam.io\/OyiZw\/fanttik-5th-anniversary-sweepstakes<\/a><br \/>\nPRIZES (US-Only): \u2764\ufe0f 50 lucky winners<\/p>\n<p>(Age requirement: At least 16 years old)<br \/>\n\ud83c\udf812*UFC Fight Night tickets in Newark on June 7<br \/>\n1*UFC store e-gift card worth $100<\/p>\n<p>4*UFC store e-gift cards worth $50<\/p>\n<p>10*UFC and Fanttik co-branded caps<\/p>\n<p>8*Fanttik screwdrivers<\/p>\n<p>25*Fanttik store coupons<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/gleam.io\/OyiZw\/fanttik-5th-anniversary-sweepstakes PRIZES (US-Only): \u2764\ufe0f 50 lucky winners (Age requirement: At least 16 years old) \ud83c\udf812*UFC Fight Night tickets in Newark on June 7 1*UFC store e-gift card worth $100 4*UFC store e-gift cards worth $50 10*UFC and Fanttik co-branded caps 8*Fanttik screwdrivers 25*Fanttik store coupons<\/p>\n","protected":false},"author":7783,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-749816","post","type-post","status-publish","format-standard","hentry","category-one-entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fanttik 5th Anniversary Sweepstakes - Free Stuff Times Contests<\/title>\n<meta name=\"description\" content=\"https:\/\/gleam.io\/OyiZw\/fanttik-5th-anniversary-sweepstakes PRIZES (US-Only): \u2764\ufe0f 50 lucky winners (Age requirement: At least 16 years old) \ud83c\udf812*UFC Fight\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fanttik 5th Anniversary Sweepstakes - Free Stuff Times Contests\" \/>\n<meta property=\"og:description\" content=\"https:\/\/gleam.io\/OyiZw\/fanttik-5th-anniversary-sweepstakes PRIZES (US-Only): \u2764\ufe0f 50 lucky winners (Age requirement: At least 16 years old) \ud83c\udf812*UFC Fight\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/\" \/>\n<meta property=\"og:site_name\" content=\"Free Stuff Times Contests\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-18T05:33:02+00:00\" \/>\n<meta name=\"author\" content=\"Chris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/18\\\/fanttik-5th-anniversary-sweepstakes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/18\\\/fanttik-5th-anniversary-sweepstakes\\\/\"},\"author\":{\"name\":\"Chris\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/person\\\/067269b17dad055936df35eebaed3589\"},\"headline\":\"Fanttik 5th Anniversary Sweepstakes\",\"datePublished\":\"2025-05-18T05:33:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/18\\\/fanttik-5th-anniversary-sweepstakes\\\/\"},\"wordCount\":48,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#organization\"},\"articleSection\":[\"One Entry\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/18\\\/fanttik-5th-anniversary-sweepstakes\\\/#respond\"]}],\"dateModified\":\"2025-05-18T01:33:02-04:00\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/18\\\/fanttik-5th-anniversary-sweepstakes\\\/\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/18\\\/fanttik-5th-anniversary-sweepstakes\\\/\",\"name\":\"Fanttik 5th Anniversary Sweepstakes - Free Stuff Times Contests\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#website\"},\"datePublished\":\"2025-05-18T05:33:02+00:00\",\"description\":\"https:\\\/\\\/gleam.io\\\/OyiZw\\\/fanttik-5th-anniversary-sweepstakes PRIZES (US-Only): \u2764\ufe0f 50 lucky winners (Age requirement: At least 16 years old) \ud83c\udf812*UFC Fight\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/18\\\/fanttik-5th-anniversary-sweepstakes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/18\\\/fanttik-5th-anniversary-sweepstakes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/18\\\/fanttik-5th-anniversary-sweepstakes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"One Entry\",\"item\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/category\\\/one-entry\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fanttik 5th Anniversary Sweepstakes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#website\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/\",\"name\":\"Free Stuff Times Contests\",\"description\":\"The Free Stuff Times Contests page is the place to go for Contests, Instant Win Games, Sweepstakes, and more!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#organization\",\"name\":\"Free Stuff Times Contests\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1200x1200cc.png\",\"contentUrl\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1200x1200cc.png\",\"width\":1200,\"height\":1200,\"caption\":\"Free Stuff Times Contests\"},\"image\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/person\\\/067269b17dad055936df35eebaed3589\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"caption\":\"Chris\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fanttik 5th Anniversary Sweepstakes - Free Stuff Times Contests","description":"https:\/\/gleam.io\/OyiZw\/fanttik-5th-anniversary-sweepstakes PRIZES (US-Only): \u2764\ufe0f 50 lucky winners (Age requirement: At least 16 years old) \ud83c\udf812*UFC Fight","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/","og_locale":"en_US","og_type":"article","og_title":"Fanttik 5th Anniversary Sweepstakes - Free Stuff Times Contests","og_description":"https:\/\/gleam.io\/OyiZw\/fanttik-5th-anniversary-sweepstakes PRIZES (US-Only): \u2764\ufe0f 50 lucky winners (Age requirement: At least 16 years old) \ud83c\udf812*UFC Fight","og_url":"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/","og_site_name":"Free Stuff Times Contests","article_published_time":"2025-05-18T05:33:02+00:00","author":"Chris","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Chris"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/#article","isPartOf":{"@id":"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/"},"author":{"name":"Chris","@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/person\/067269b17dad055936df35eebaed3589"},"headline":"Fanttik 5th Anniversary Sweepstakes","datePublished":"2025-05-18T05:33:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/"},"wordCount":48,"commentCount":0,"publisher":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#organization"},"articleSection":["One Entry"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/#respond"]}],"dateModified":"2025-05-18T01:33:02-04:00"},{"@type":"WebPage","@id":"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/","url":"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/","name":"Fanttik 5th Anniversary Sweepstakes - Free Stuff Times Contests","isPartOf":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#website"},"datePublished":"2025-05-18T05:33:02+00:00","description":"https:\/\/gleam.io\/OyiZw\/fanttik-5th-anniversary-sweepstakes PRIZES (US-Only): \u2764\ufe0f 50 lucky winners (Age requirement: At least 16 years old) \ud83c\udf812*UFC Fight","breadcrumb":{"@id":"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.freestufftimes.com\/contests\/18\/fanttik-5th-anniversary-sweepstakes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.freestufftimes.com\/contests\/"},{"@type":"ListItem","position":2,"name":"One Entry","item":"https:\/\/www.freestufftimes.com\/contests\/category\/one-entry\/"},{"@type":"ListItem","position":3,"name":"Fanttik 5th Anniversary Sweepstakes"}]},{"@type":"WebSite","@id":"https:\/\/www.freestufftimes.com\/contests\/#website","url":"https:\/\/www.freestufftimes.com\/contests\/","name":"Free Stuff Times Contests","description":"The Free Stuff Times Contests page is the place to go for Contests, Instant Win Games, Sweepstakes, and more!","publisher":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#organization"},"potentialAction":[{"@type":"SearchAction","target":"https:\/\/www.freestufftimes.com\/contests\/?s={search_term_string}","query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.freestufftimes.com\/contests\/#organization","name":"Free Stuff Times Contests","url":"https:\/\/www.freestufftimes.com\/contests\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/logo\/image\/","url":"https:\/\/www.freestufftimes.com\/contests\/wp-content\/uploads\/2026\/05\/1200x1200cc.png","contentUrl":"https:\/\/www.freestufftimes.com\/contests\/wp-content\/uploads\/2026\/05\/1200x1200cc.png","width":1200,"height":1200,"caption":"Free Stuff Times Contests"},"image":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/person\/067269b17dad055936df35eebaed3589","name":"Chris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","caption":"Chris"}}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2mit9-393O","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/posts\/749816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/users\/7783"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/comments?post=749816"}],"version-history":[{"count":0,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/posts\/749816\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/media?parent=749816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/categories?post=749816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/tags?post=749816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}