{"id":333022,"date":"2014-09-19T15:02:09","date_gmt":"2014-09-19T19:02:09","guid":{"rendered":"http:\/\/www.freestufftimes.com\/contests\/?p=333022"},"modified":"2014-09-19T15:02:09","modified_gmt":"2014-09-19T19:02:09","slug":"aafa-clean-win-sweepstakes-2","status":"publish","type":"post","link":"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/","title":{"rendered":"AAFA \u201cCLEAN UP &#038; WIN\u201d SWEEPSTAKES"},"content":{"rendered":"<p><a href=\"http:\/\/woobox.com\/6v2k4n\/a2o37k\"  target=\"_blank\">https:\/\/www.facebook.com\/AAFANational?sk=app_143103275748075 <\/a>\u00a0thanks gigi<br \/>\nWin 1 of 2 Dyson DC65 \u00a0vacuums<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.facebook.com\/AAFANational?sk=app_143103275748075 \u00a0thanks gigi Win 1 of 2 Dyson DC65 \u00a0vacuums<\/p>\n","protected":false},"author":7783,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-333022","post","type-post","status-publish","format-standard","hentry","category-one-entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AAFA \u201cCLEAN UP &amp; WIN\u201d SWEEPSTAKES - Free Stuff Times Contests<\/title>\n<meta name=\"description\" content=\"https:\/\/www.facebook.com\/AAFANational?sk=app_143103275748075 \u00a0thanks gigi Win 1 of 2 Dyson DC65 \u00a0vacuums\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AAFA \u201cCLEAN UP &amp; WIN\u201d SWEEPSTAKES - Free Stuff Times Contests\" \/>\n<meta property=\"og:description\" content=\"https:\/\/www.facebook.com\/AAFANational?sk=app_143103275748075 \u00a0thanks gigi Win 1 of 2 Dyson DC65 \u00a0vacuums\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Free Stuff Times Contests\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-19T19:02:09+00:00\" \/>\n<meta name=\"author\" content=\"Chris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/19\\\/aafa-clean-win-sweepstakes-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/19\\\/aafa-clean-win-sweepstakes-2\\\/\"},\"author\":{\"name\":\"Chris\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/person\\\/067269b17dad055936df35eebaed3589\"},\"headline\":\"AAFA \u201cCLEAN UP &#038; WIN\u201d SWEEPSTAKES\",\"datePublished\":\"2014-09-19T19:02:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/19\\\/aafa-clean-win-sweepstakes-2\\\/\"},\"wordCount\":19,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#organization\"},\"articleSection\":[\"One Entry\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/19\\\/aafa-clean-win-sweepstakes-2\\\/#respond\"]}],\"dateModified\":\"2014-09-19T15:02:09-04:00\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/19\\\/aafa-clean-win-sweepstakes-2\\\/\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/19\\\/aafa-clean-win-sweepstakes-2\\\/\",\"name\":\"AAFA \u201cCLEAN UP & WIN\u201d SWEEPSTAKES - Free Stuff Times Contests\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#website\"},\"datePublished\":\"2014-09-19T19:02:09+00:00\",\"description\":\"https:\\\/\\\/www.facebook.com\\\/AAFANational?sk=app_143103275748075 \u00a0thanks gigi Win 1 of 2 Dyson DC65 \u00a0vacuums\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/19\\\/aafa-clean-win-sweepstakes-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/19\\\/aafa-clean-win-sweepstakes-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/19\\\/aafa-clean-win-sweepstakes-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"One Entry\",\"item\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/category\\\/one-entry\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AAFA \u201cCLEAN UP &#038; WIN\u201d SWEEPSTAKES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#website\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/\",\"name\":\"Free Stuff Times Contests\",\"description\":\"The Free Stuff Times Contests page is the place to go for Contests, Instant Win Games, Sweepstakes, and more!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#organization\",\"name\":\"Free Stuff Times Contests\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1200x1200cc.png\",\"contentUrl\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1200x1200cc.png\",\"width\":1200,\"height\":1200,\"caption\":\"Free Stuff Times Contests\"},\"image\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/person\\\/067269b17dad055936df35eebaed3589\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"caption\":\"Chris\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AAFA \u201cCLEAN UP & WIN\u201d SWEEPSTAKES - Free Stuff Times Contests","description":"https:\/\/www.facebook.com\/AAFANational?sk=app_143103275748075 \u00a0thanks gigi Win 1 of 2 Dyson DC65 \u00a0vacuums","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/","og_locale":"en_US","og_type":"article","og_title":"AAFA \u201cCLEAN UP & WIN\u201d SWEEPSTAKES - Free Stuff Times Contests","og_description":"https:\/\/www.facebook.com\/AAFANational?sk=app_143103275748075 \u00a0thanks gigi Win 1 of 2 Dyson DC65 \u00a0vacuums","og_url":"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/","og_site_name":"Free Stuff Times Contests","article_published_time":"2014-09-19T19:02:09+00:00","author":"Chris","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Chris"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/#article","isPartOf":{"@id":"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/"},"author":{"name":"Chris","@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/person\/067269b17dad055936df35eebaed3589"},"headline":"AAFA \u201cCLEAN UP &#038; WIN\u201d SWEEPSTAKES","datePublished":"2014-09-19T19:02:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/"},"wordCount":19,"commentCount":0,"publisher":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#organization"},"articleSection":["One Entry"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/#respond"]}],"dateModified":"2014-09-19T15:02:09-04:00"},{"@type":"WebPage","@id":"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/","url":"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/","name":"AAFA \u201cCLEAN UP & WIN\u201d SWEEPSTAKES - Free Stuff Times Contests","isPartOf":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#website"},"datePublished":"2014-09-19T19:02:09+00:00","description":"https:\/\/www.facebook.com\/AAFANational?sk=app_143103275748075 \u00a0thanks gigi Win 1 of 2 Dyson DC65 \u00a0vacuums","breadcrumb":{"@id":"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.freestufftimes.com\/contests\/19\/aafa-clean-win-sweepstakes-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.freestufftimes.com\/contests\/"},{"@type":"ListItem","position":2,"name":"One Entry","item":"https:\/\/www.freestufftimes.com\/contests\/category\/one-entry\/"},{"@type":"ListItem","position":3,"name":"AAFA \u201cCLEAN UP &#038; WIN\u201d SWEEPSTAKES"}]},{"@type":"WebSite","@id":"https:\/\/www.freestufftimes.com\/contests\/#website","url":"https:\/\/www.freestufftimes.com\/contests\/","name":"Free Stuff Times Contests","description":"The Free Stuff Times Contests page is the place to go for Contests, Instant Win Games, Sweepstakes, and more!","publisher":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#organization"},"potentialAction":[{"@type":"SearchAction","target":"https:\/\/www.freestufftimes.com\/contests\/?s={search_term_string}","query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.freestufftimes.com\/contests\/#organization","name":"Free Stuff Times Contests","url":"https:\/\/www.freestufftimes.com\/contests\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/logo\/image\/","url":"https:\/\/www.freestufftimes.com\/contests\/wp-content\/uploads\/2026\/05\/1200x1200cc.png","contentUrl":"https:\/\/www.freestufftimes.com\/contests\/wp-content\/uploads\/2026\/05\/1200x1200cc.png","width":1200,"height":1200,"caption":"Free Stuff Times Contests"},"image":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/person\/067269b17dad055936df35eebaed3589","name":"Chris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","caption":"Chris"}}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2mit9-1oDk","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/posts\/333022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/users\/7783"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/comments?post=333022"}],"version-history":[{"count":0,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/posts\/333022\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/media?parent=333022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/categories?post=333022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/tags?post=333022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}