{"id":317987,"date":"2014-01-13T15:23:31","date_gmt":"2014-01-13T20:23:31","guid":{"rendered":"http:\/\/www.freestufftimes.com\/contests\/?p=317987"},"modified":"2014-01-13T15:23:31","modified_gmt":"2014-01-13T20:23:31","slug":"lays-us-flavor-choose-chip-contest","status":"publish","type":"post","link":"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/","title":{"rendered":"LAY&#8217;S Do Us A Flavor Choose Your Chip Contest"},"content":{"rendered":"<p><a target=\"_blank\" href=\"https:\/\/www.dousaflavor.com\/#!\/\" >https:\/\/www.dousaflavor.com\/#!\/<\/a><\/p>\n<p>Finalist Prizes (3): Fifty Thousand dollars ($50,000), awarded in the form of a check or wire transfer, payable to winner. Approximate Retail Value (\u201cARV\u201d): $50,000 each. Grand Prize winner is not eligible to receive a Finalist Prize.<\/p>\n<p>Finalist Prize Payout Terms: Finalist Prizes will be awarded after the Grand Prize Winner has been identified and verified. Allow 6-8 weeks upon Grand Prize Winner verification for Finalist Prizes to be awarded.<\/p>\n<p>Grand Prize (1): The Grand Prize Winner shall be entitled to receive the greater of:<\/p>\n<p>(a) One percent (1%) of the Net Sales* of the Grand Prize Winner\u2019s Finalist Flavor for the period July 1, 2014 through July 1, 2015 (the \u201cSales Period\u201d);<\/p>\n<p>OR<\/p>\n<p>(b) One Million Dollars ($1,000,000). Awarded in the form of a check or wire transfer, payable to winner. ARV: $1,000,000.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.dousaflavor.com\/#!\/ Finalist Prizes (3): Fifty Thousand dollars ($50,000), awarded in the form of a check or wire transfer, payable to winner. Approximate Retail Value (\u201cARV\u201d): $50,000 each. Grand Prize winner is not eligible to receive a Finalist Prize. Finalist Prize Payout Terms: Finalist Prizes will be awarded after the Grand Prize Winner has been identified [&hellip;]<\/p>\n","protected":false},"author":7783,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-317987","post","type-post","status-publish","format-standard","hentry","category-unlimited"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LAY&#039;S Do Us A Flavor Choose Your Chip Contest - Free Stuff Times Contests<\/title>\n<meta name=\"description\" content=\"https:\/\/www.dousaflavor.com\/#!\/ Finalist Prizes (3): Fifty Thousand dollars ($50,000), awarded in the form of a check or wire transfer, payable to winner.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LAY&#039;S Do Us A Flavor Choose Your Chip Contest - Free Stuff Times Contests\" \/>\n<meta property=\"og:description\" content=\"https:\/\/www.dousaflavor.com\/#!\/ Finalist Prizes (3): Fifty Thousand dollars ($50,000), awarded in the form of a check or wire transfer, payable to winner.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/\" \/>\n<meta property=\"og:site_name\" content=\"Free Stuff Times Contests\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-13T20:23:31+00:00\" \/>\n<meta name=\"author\" content=\"Chris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/13\\\/lays-us-flavor-choose-chip-contest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/13\\\/lays-us-flavor-choose-chip-contest\\\/\"},\"author\":{\"name\":\"Chris\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/person\\\/067269b17dad055936df35eebaed3589\"},\"headline\":\"LAY&#8217;S Do Us A Flavor Choose Your Chip Contest\",\"datePublished\":\"2014-01-13T20:23:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/13\\\/lays-us-flavor-choose-chip-contest\\\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#organization\"},\"articleSection\":[\"Unlimited\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/13\\\/lays-us-flavor-choose-chip-contest\\\/#respond\"]}],\"dateModified\":\"2014-01-13T15:23:31-05:00\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/13\\\/lays-us-flavor-choose-chip-contest\\\/\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/13\\\/lays-us-flavor-choose-chip-contest\\\/\",\"name\":\"LAY'S Do Us A Flavor Choose Your Chip Contest - Free Stuff Times Contests\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#website\"},\"datePublished\":\"2014-01-13T20:23:31+00:00\",\"description\":\"https:\\\/\\\/www.dousaflavor.com\\\/#!\\\/ Finalist Prizes (3): Fifty Thousand dollars ($50,000), awarded in the form of a check or wire transfer, payable to winner.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/13\\\/lays-us-flavor-choose-chip-contest\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/13\\\/lays-us-flavor-choose-chip-contest\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/13\\\/lays-us-flavor-choose-chip-contest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unlimited\",\"item\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/category\\\/unlimited\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LAY&#8217;S Do Us A Flavor Choose Your Chip Contest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#website\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/\",\"name\":\"Free Stuff Times Contests\",\"description\":\"The Free Stuff Times Contests page is the place to go for Contests, Instant Win Games, Sweepstakes, and more!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#organization\",\"name\":\"Free Stuff Times Contests\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1200x1200cc.png\",\"contentUrl\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1200x1200cc.png\",\"width\":1200,\"height\":1200,\"caption\":\"Free Stuff Times Contests\"},\"image\":{\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.freestufftimes.com\\\/contests\\\/#\\\/schema\\\/person\\\/067269b17dad055936df35eebaed3589\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g\",\"caption\":\"Chris\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LAY'S Do Us A Flavor Choose Your Chip Contest - Free Stuff Times Contests","description":"https:\/\/www.dousaflavor.com\/#!\/ Finalist Prizes (3): Fifty Thousand dollars ($50,000), awarded in the form of a check or wire transfer, payable to winner.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/","og_locale":"en_US","og_type":"article","og_title":"LAY'S Do Us A Flavor Choose Your Chip Contest - Free Stuff Times Contests","og_description":"https:\/\/www.dousaflavor.com\/#!\/ Finalist Prizes (3): Fifty Thousand dollars ($50,000), awarded in the form of a check or wire transfer, payable to winner.","og_url":"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/","og_site_name":"Free Stuff Times Contests","article_published_time":"2014-01-13T20:23:31+00:00","author":"Chris","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Chris","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/#article","isPartOf":{"@id":"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/"},"author":{"name":"Chris","@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/person\/067269b17dad055936df35eebaed3589"},"headline":"LAY&#8217;S Do Us A Flavor Choose Your Chip Contest","datePublished":"2014-01-13T20:23:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#organization"},"articleSection":["Unlimited"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/#respond"]}],"dateModified":"2014-01-13T15:23:31-05:00"},{"@type":"WebPage","@id":"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/","url":"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/","name":"LAY'S Do Us A Flavor Choose Your Chip Contest - Free Stuff Times Contests","isPartOf":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#website"},"datePublished":"2014-01-13T20:23:31+00:00","description":"https:\/\/www.dousaflavor.com\/#!\/ Finalist Prizes (3): Fifty Thousand dollars ($50,000), awarded in the form of a check or wire transfer, payable to winner.","breadcrumb":{"@id":"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.freestufftimes.com\/contests\/13\/lays-us-flavor-choose-chip-contest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.freestufftimes.com\/contests\/"},{"@type":"ListItem","position":2,"name":"Unlimited","item":"https:\/\/www.freestufftimes.com\/contests\/category\/unlimited\/"},{"@type":"ListItem","position":3,"name":"LAY&#8217;S Do Us A Flavor Choose Your Chip Contest"}]},{"@type":"WebSite","@id":"https:\/\/www.freestufftimes.com\/contests\/#website","url":"https:\/\/www.freestufftimes.com\/contests\/","name":"Free Stuff Times Contests","description":"The Free Stuff Times Contests page is the place to go for Contests, Instant Win Games, Sweepstakes, and more!","publisher":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#organization"},"potentialAction":[{"@type":"SearchAction","target":"https:\/\/www.freestufftimes.com\/contests\/?s={search_term_string}","query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.freestufftimes.com\/contests\/#organization","name":"Free Stuff Times Contests","url":"https:\/\/www.freestufftimes.com\/contests\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/logo\/image\/","url":"https:\/\/www.freestufftimes.com\/contests\/wp-content\/uploads\/2026\/05\/1200x1200cc.png","contentUrl":"https:\/\/www.freestufftimes.com\/contests\/wp-content\/uploads\/2026\/05\/1200x1200cc.png","width":1200,"height":1200,"caption":"Free Stuff Times Contests"},"image":{"@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.freestufftimes.com\/contests\/#\/schema\/person\/067269b17dad055936df35eebaed3589","name":"Chris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90fded9c52f40c42eed30c6bcaca442ecb2938833a74d5e7c676e5bd4756614a?s=96&d=mm&r=g","caption":"Chris"}}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2mit9-1kIP","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/posts\/317987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/users\/7783"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/comments?post=317987"}],"version-history":[{"count":0,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/posts\/317987\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/media?parent=317987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/categories?post=317987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.freestufftimes.com\/contests\/wp-json\/wp\/v2\/tags?post=317987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}